{"id":1243,"count":1,"description":"","link":"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/","name":"Pablo Di Lorenzo","slug":"pablo-di-lorenzo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pablo Di Lorenzo archivos - Diario del Oeste<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pablo Di Lorenzo archivos - Diario del Oeste\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario del Oeste\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/tag\\\/pablo-di-lorenzo\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/tag\\\/pablo-di-lorenzo\\\/\",\"name\":\"Pablo Di Lorenzo archivos - Diario del Oeste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/tag\\\/pablo-di-lorenzo\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/tag\\\/pablo-di-lorenzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pablo Di Lorenzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"name\":\"Diario del Oeste\",\"description\":\"Noticias del Oeste\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\",\"name\":\"Diario del Oeste\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"width\":306,\"height\":145,\"caption\":\"Diario del Oeste\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pablo Di Lorenzo archivos - Diario del Oeste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/","og_locale":"es_ES","og_type":"article","og_title":"Pablo Di Lorenzo archivos - Diario del Oeste","og_url":"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/","og_site_name":"Diario del Oeste","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/","url":"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/","name":"Pablo Di Lorenzo archivos - Diario del Oeste","isPartOf":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#website"},"breadcrumb":{"@id":"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/#breadcrumb"},"inLanguage":"es-AR"},{"@type":"BreadcrumbList","@id":"https:\/\/diariodeloeste.com\/noticias\/tag\/pablo-di-lorenzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/diariodeloeste.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"Pablo Di Lorenzo"}]},{"@type":"WebSite","@id":"https:\/\/diariodeloeste.com\/noticias\/#website","url":"https:\/\/diariodeloeste.com\/noticias\/","name":"Diario del Oeste","description":"Noticias del Oeste","publisher":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodeloeste.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/diariodeloeste.com\/noticias\/#organization","name":"Diario del Oeste","url":"https:\/\/diariodeloeste.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","contentUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","width":306,"height":145,"caption":"Diario del Oeste"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/tags\/1243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts?tags=1243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}