{"id":1678,"date":"2018-07-09T13:03:28","date_gmt":"2018-07-09T13:03:28","guid":{"rendered":"https:\/\/diariodeloeste.com\/noticias\/?p=1678"},"modified":"2018-07-09T13:03:28","modified_gmt":"2018-07-09T13:03:28","slug":"que-paso-realmente-en-tucuman-en-1816-por-patricio-lons","status":"publish","type":"post","link":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/","title":{"rendered":"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons"},"content":{"rendered":"<p style=\"font-weight: 400;\"><strong><em>Nuestra independencia es algo curiosa, pues tuvimos una fecha anterior a mediados de 1815 en el llamado Congreso de Oriente, convocado por el general Artigas.&nbsp;&nbsp;Las actas de este congreso se perdieron y las de la independencia de 1816 se perdieron en 1927.&nbsp;<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">Por lo tanto no hay constancia de muchas cosas, si se discuti\u00f3 que territorio concreto se independizaba y cual se pretend\u00eda a futuro, cu\u00e1l iba a ser la religi\u00f3n y la lengua oficial, que sistema de gobierno iba a regir al nuevo pa\u00eds, si se iban a mantener las Leyes de Indias o cambiar por un modelo judicial de otro tipo,&nbsp; cu\u00e1les ser\u00edan sus objetivos geopol\u00edticos respecto al resto de Am\u00e9rica hisp\u00e1nica, de Espa\u00f1a misma y del resto de Europa y de la Am\u00e9rica anglosajona, que moneda iba a circular y con qu\u00e9 paridad y sustento o si se buscar\u00eda mantener junto al resto del continente al Real de a Ocho que era una moneda global m\u00e1s fuerte que la libra, cu\u00e1l iba a ser el modelo educativo y el proyecto econ\u00f3mico, de qu\u00e9 manera iba a seguir el proceso de integraci\u00f3n de los pueblos abor\u00edgenes, si se les iba a respetar a estos, las tierras que la corona les reconoc\u00eda con su sistema aut\u00f3nomo de rep\u00fablicas de indios, m\u00e1s todos los acuerdos entre la corona y las distintas poblaciones abor\u00edgenes, si se iba a mantener la integridad del virreinato y por ende, si se iba a invitar&nbsp; a los pueblos de Guinea Ecuatorial que pertenec\u00edan al Virreinato del R\u00edo de la Plata, etc.<\/p>\n<p style=\"font-weight: 400;\">Otro tema que, por el contrario queda muy claro, es la falta de federalismo, manifestado en una odiosa enemistad hacia Artigas, que ya hab\u00eda declarado la independencia en 1815 en Arroyo de la China.&nbsp; Incluso, nuestros pr\u00f3ceres de la independencia, pocos meses despu\u00e9s de declararse independientes de Espa\u00f1a, el 9 de julio de 1816, se manifestaron dispuestos a pasar a depender del gobierno del Brasil, ya que este estaba por invadir la Banda Oriental (Uruguay) y amenazaba a las Provincias Unidas del Plata. Las cartas y los comisionados no llegaron a R\u00edo de Janeiro. Es que Pueyrred\u00f3n (de origen gasc\u00f3n), no cre\u00eda necesario entregar el pa\u00eds al Brasil para salvarlo del artiguismo. Prefer\u00eda entreg\u00e1rselo a Francia, tierra de sus ancestros, antes de mantener la unidad continental heredada de Espa\u00f1a.<\/p>\n<p style=\"font-weight: 400;\">Vemos que nuestros pr\u00f3ceres eran muy regaladores con lo que no era suyo. Ninguno propuso reunificarnos con el virreinato del Per\u00fa, que nos hubiese asegurado nuestra condici\u00f3n de potencia bioce\u00e1nica, condici\u00f3n que EEUU, reci\u00e9n consigui\u00f3 en la segunda mitad del siglo XIX y a trav\u00e9s de guerras contra M\u00e9jico.&nbsp;<\/p>\n<p style=\"font-weight: 400;\">Nosotros lo ten\u00edamos de forma y derecho natural por estar unidos al Alto Per\u00fa y lo perdimos.<\/p>\n<p style=\"font-weight: 400;\">Otro aspecto del entreguismo iniciado en esos a\u00f1os, lo representa Carlos Mar\u00eda de Alvear.&nbsp; Lleg\u00f3 a ofrecer las Provincias Unidas al embajador brit\u00e1nico en el Brasil como sumisas colonias de Su Majestad<strong><em>. &#8220;Estas provincias desean pertenecer a la Gran Breta\u00f1a, recibir sus leyes, obedecer a su gobierno y vivir bajo su influjo poderoso.&#8221;&nbsp;<\/em><\/strong>Eso y m\u00e1s le escribi\u00f3 Alvear al ministro Castlereagh, por suerte la carta que iba dirigida a este funcionario ingl\u00e9s es interceptada por Belgrano y Rivadavia que se encontraban en R\u00edo de Janeiro en misi\u00f3n oficial. El encargado de llevar las cartas al embajador Strangford fue Manuel Garc\u00eda, uno de los personajes m\u00e1s nefastos de la historia argentina, que a\u00f1os posteriores gestionar\u00e1 el famoso empr\u00e9stito de un mill\u00f3n de libras esterlinas con la banca Baring Brothers (primer gran negociado argentino); y luego en 1827 tras la victoria argentina de Ituzaing\u00f3, firmar\u00e1 el acuerdo de paz con el derrotado emperador del Brasil, por el cual Uruguay pasa a ser un pa\u00eds aut\u00f3nomo e independiente.<\/p>\n<p style=\"font-weight: 400;\">&nbsp;Lo concreto es que perdimos Guinea, el Alto Per\u00fa, la Banda Oriental y con ellas, la salida al Pac\u00edfico y el control del R\u00edo de la Plata y una base pol\u00edtica, militar y comercial en \u00c1frica. Tambi\u00e9n nos desentendimos de buscar un acuerdo con el Paraguay y Chile y la Patagonia y el sur de Chile, quedaron en un limbo. &nbsp;Y esas partes de la patria nos perdieron a nosotros. Solo con Roca, d\u00e9cadas despu\u00e9s se asegur\u00f3 la Patagonia argentina.<\/p>\n<p style=\"font-weight: 400;\">Con esas p\u00e9rdidas de m\u00e1s de un mill\u00f3n y medio de kil\u00f3metros cuadrados, se perdi\u00f3 el comercio con Asia y el predominio de nuestra poderosa moneda de dominio global, el real de&nbsp; a ocho. Se impidi\u00f3 que asumiera Jos\u00e9 Moldes, general salte\u00f1o, como presidente del nuevo gobierno, que pretend\u00eda evitar el centralismo de Buenos Aires, incluso se lo secuestr\u00f3 y Belgrano lo envi\u00f3 preso a Chile, donde detenido por San Mart\u00edn, muere en extra\u00f1as circunstancias.<\/p>\n<p style=\"font-weight: 400;\">En paralelo al congreso, en Buenos Aires, los comerciantes ingleses ya pensaban en su dominio y en un futuro tratado de comercio y navegaci\u00f3n con nosotros, lo que consiguen en 1825, cuando Las Heras, ex jefe de Estado Mayor de San Mart\u00edn, firma el Tratado de comercio y navegaci\u00f3n entre Inglaterra y nosotros, que signific\u00f3 la sujeci\u00f3n de nuestra patria desde entonces y hasta ahora.<\/p>\n<p style=\"font-weight: 400;\">Se terminaron centralizando los intereses comerciales del puerto de Buenos Aires en desmedro del interior y avasallando los derechos de los pueblos ind\u00edgenas a los que se les robaron sus tierras y se los masacr\u00f3 en la Banda Oriental all\u00e1 por 1830. Por eso, la mayor\u00eda de ellos, que ve\u00edan el esp\u00edritu materialista de la revoluci\u00f3n, se mantuvieron realistas m\u00e1s all\u00e1 de la batalla de Ayacucho de 1824, mostrando m\u00e1s dignidad y fidelidad a la fe, que muchos oficiales espa\u00f1oles que traicionaron en esa \u00faltima batalla.<\/p>\n<p style=\"font-weight: 400;\">Dejamos de ser una gran potencia junto a las naciones hermanas de Am\u00e9rica y Espa\u00f1a, que fuimos paridas juntas en 1492, para ser m\u00e1s de veinte estados, algunos de tama\u00f1o de una municipalidad y otro absolutamente mediterr\u00e1neo, con escasas posibilidades de escapar del dominio ingl\u00e9s.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"font-weight: 400;\">EN DEFINITIVA, GRACIAS A NUESTROS PR\u00d3CERES, SE IMPUSIERON LOS OBJETIVOS COMERCIALES Y POL\u00cdTICOS DE GRAN BRETA\u00d1A.<\/p>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p>Nuestra independencia es algo curiosa, pues tuvimos una fecha anterior a mediados de 1815 en el llamado Congreso de Oriente, convocado por el general Artigas.&nbsp;&nbsp;Las actas de este congreso se perdieron y las de la independencia de 1816 se perdieron en 1927.&nbsp; &nbsp; Por lo tanto no hay constancia de muchas cosas, si se discuti\u00f3 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[14,9],"tags":[],"class_list":["post-1678","post","type-post","status-publish","format-standard","has-post-thumbnail","category-informacion-general","category-titulares"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons - Diario del Oeste<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons - Diario del Oeste\" \/>\n<meta property=\"og:description\" content=\"Nuestra independencia es algo curiosa, pues tuvimos una fecha anterior a mediados de 1815 en el llamado Congreso de Oriente, convocado por el general Artigas.&nbsp;&nbsp;Las actas de este congreso se perdieron y las de la independencia de 1816 se perdieron en 1927.&nbsp; &nbsp; Por lo tanto no hay constancia de muchas cosas, si se discuti\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario del Oeste\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-09T13:03:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2018\/07\/dia-de-la-independencia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"520\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/person\\\/fe4f8b89d0c447922571265f616af325\"},\"headline\":\"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons\",\"datePublished\":\"2018-07-09T13:03:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/\"},\"wordCount\":1092,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/dia-de-la-independencia.jpg\",\"articleSection\":[\"Informaci\u00f3n General\",\"Titulares\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/\",\"name\":\"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons - Diario del Oeste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/dia-de-la-independencia.jpg\",\"datePublished\":\"2018-07-09T13:03:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/dia-de-la-independencia.jpg\",\"contentUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/dia-de-la-independencia.jpg\",\"width\":800,\"height\":520},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2018\\\/07\\\/09\\\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"name\":\"Diario del Oeste\",\"description\":\"Noticias del Oeste\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\",\"name\":\"Diario del Oeste\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"width\":306,\"height\":145,\"caption\":\"Diario del Oeste\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/person\\\/fe4f8b89d0c447922571265f616af325\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1dcbae4a1eda6214c7bc9115f54e8889dd662450ef0ab6cb929af1bf9054141?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1dcbae4a1eda6214c7bc9115f54e8889dd662450ef0ab6cb929af1bf9054141?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c1dcbae4a1eda6214c7bc9115f54e8889dd662450ef0ab6cb929af1bf9054141?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons - Diario del Oeste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons - Diario del Oeste","og_description":"Nuestra independencia es algo curiosa, pues tuvimos una fecha anterior a mediados de 1815 en el llamado Congreso de Oriente, convocado por el general Artigas.&nbsp;&nbsp;Las actas de este congreso se perdieron y las de la independencia de 1816 se perdieron en 1927.&nbsp; &nbsp; Por lo tanto no hay constancia de muchas cosas, si se discuti\u00f3 [&hellip;]","og_url":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/","og_site_name":"Diario del Oeste","article_published_time":"2018-07-09T13:03:28+00:00","og_image":[{"width":800,"height":520,"url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2018\/07\/dia-de-la-independencia.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/#article","isPartOf":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/"},"author":{"name":"admin","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/person\/fe4f8b89d0c447922571265f616af325"},"headline":"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons","datePublished":"2018-07-09T13:03:28+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/"},"wordCount":1092,"publisher":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#organization"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2018\/07\/dia-de-la-independencia.jpg","articleSection":["Informaci\u00f3n General","Titulares"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/","url":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/","name":"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons - Diario del Oeste","isPartOf":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/#primaryimage"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2018\/07\/dia-de-la-independencia.jpg","datePublished":"2018-07-09T13:03:28+00:00","breadcrumb":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/#primaryimage","url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2018\/07\/dia-de-la-independencia.jpg","contentUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2018\/07\/dia-de-la-independencia.jpg","width":800,"height":520},{"@type":"BreadcrumbList","@id":"https:\/\/diariodeloeste.com\/noticias\/2018\/07\/09\/que-paso-realmente-en-tucuman-en-1816-por-patricio-lons\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/diariodeloeste.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"\u00bfQUE PAS\u00d3 REALMENTE EN TUCUM\u00c1N EN 1816? por Patricio Lons"}]},{"@type":"WebSite","@id":"https:\/\/diariodeloeste.com\/noticias\/#website","url":"https:\/\/diariodeloeste.com\/noticias\/","name":"Diario del Oeste","description":"Noticias del Oeste","publisher":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodeloeste.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/diariodeloeste.com\/noticias\/#organization","name":"Diario del Oeste","url":"https:\/\/diariodeloeste.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","contentUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","width":306,"height":145,"caption":"Diario del Oeste"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/person\/fe4f8b89d0c447922571265f616af325","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/c1dcbae4a1eda6214c7bc9115f54e8889dd662450ef0ab6cb929af1bf9054141?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c1dcbae4a1eda6214c7bc9115f54e8889dd662450ef0ab6cb929af1bf9054141?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c1dcbae4a1eda6214c7bc9115f54e8889dd662450ef0ab6cb929af1bf9054141?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/diariodeloeste.com\/noticias\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/1678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/comments?post=1678"}],"version-history":[{"count":1,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/1678\/revisions"}],"predecessor-version":[{"id":1680,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/1678\/revisions\/1680"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/media\/1679"}],"wp:attachment":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/media?parent=1678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/categories?post=1678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/tags?post=1678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}