{"id":15959,"date":"2026-06-02T19:34:26","date_gmt":"2026-06-02T19:34:26","guid":{"rendered":"https:\/\/diariodeloeste.com\/noticias\/?p=15959"},"modified":"2026-06-02T19:34:26","modified_gmt":"2026-06-02T19:34:26","slug":"mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura","status":"publish","type":"post","link":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/","title":{"rendered":"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura"},"content":{"rendered":"<h2>M\u00e1s San Miguel denunci\u00f3 un nuevo episodio de persecuci\u00f3n pol\u00edtica por parte del Municipio de San Miguel luego de que inspectores municipales notificaran un acta de suspensi\u00f3n y una amenaza de clausura durante la realizaci\u00f3n de una nueva fecha de Eje de la Rima, un evento cultural y juvenil que se desarrolla mensualmente en su local partidario.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-15965 size-large\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-1024x768.jpeg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-1024x768.jpeg 1024w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-300x225.jpeg 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-768x576.jpeg 768w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-860x645.jpeg 860w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<p>La actividad, vinculada a la cultura urbana y al freestyle, se realiza desde hace cinco meses y ya hab\u00eda llevado adelante cuatro ediciones sin inconvenientes. Sin embargo, tras la \u00faltima jornada, el Municipio intervino con una medida que desde la organizaci\u00f3n consideran arbitraria y sin fundamentos t\u00e9cnicos.<\/p>\n<p>En un comunicado difundido tras los hechos, los organizadores de Eje de la Rima manifestaron su preocupaci\u00f3n por la intimaci\u00f3n recibida y remarcaron que la competencia cuenta con m\u00e1s de diez a\u00f1os de trayectoria en San Miguel. Adem\u00e1s, recordaron que en 2019 fue declarada de Inter\u00e9s Municipal y se\u00f1alaron que las dificultades comenzaron luego de que la actividad encontrara acompa\u00f1amiento fuera del oficialismo local.<\/p>\n<p>&#8220;El Eje de la Rima nunca cambi\u00f3. Lo que cambi\u00f3 fue qui\u00e9n decidi\u00f3 acompa\u00f1arnos&#8221;, expresaron. Desde M\u00e1s San Miguel se\u00f1alaron que el hecho no constituye un caso aislado, sino que forma parte de una serie de obst\u00e1culos que vienen sufriendo desde hace m\u00e1s de un a\u00f1o para desarrollar actividades sociales, culturales y comunitarias en el distrito.<\/p>\n<p>Seg\u00fan indicaron, en ese per\u00edodo se registraron decenas de actividades suspendidas o impedidas. Entre los antecedentes mencionaron la suspensi\u00f3n de operativos de salud impulsados por la Provincia de Buenos Aires que contaban con las autorizaciones correspondientes; as\u00ed como la interrupci\u00f3n violenta de la jornada de la Campa\u00f1a de Invierno organizada por el Ministerio de Desarrollo de la Comunidad de la Provincia de Buenos Aires que se realiz\u00f3 en la Plaza San Miguel, destinada a asistir a personas en situaci\u00f3n de calle.<\/p>\n<p>A ello se le sumaron antecedentes como la suspensi\u00f3n de los carnavales populares, as\u00ed como clausuras y restricciones que alcanzaron a instituciones y clubes vinculados al espacio M\u00e1s San Miguel. &#8220;Lo que observamos es una pr\u00e1ctica sistem\u00e1tica dirigida particularmente contra nuestro espacio.<\/p>\n<p>Existe un patr\u00f3n de utilizaci\u00f3n discrecional de herramientas administrativas y coercitivas para impedir o dificultar actividades impulsadas por M\u00e1s San Miguel y por organizaciones que articulan con nosotros&#8221;, se\u00f1alaron desde la organizaci\u00f3n.<\/p>\n<p>Desde M\u00e1s San Miguel anticiparon que continuar\u00e1n desarrollando actividades abiertas a la comunidad y reclamaron que se garantice la libertad de organizaci\u00f3n, participaci\u00f3n y expresi\u00f3n de todos los sectores pol\u00edticos, sociales, culturales y comunitarios del distrito.<\/p>\n<div id='gallery-1' class='gallery galleryid-15959 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/whatsapp-image-2026-06-02-at-4-20-06-pm\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM-300x225.jpeg 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM-1024x768.jpeg 1024w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM-768x576.jpeg 768w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM-860x645.jpeg 860w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/whatsapp-image-2026-06-02-at-4-20-05-pm-2\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-300x200.jpeg 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-1024x684.jpeg 1024w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-768x513.jpeg 768w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-330x220.jpeg 330w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-420x280.jpeg 420w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-615x410.jpeg 615w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2-860x574.jpeg 860w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-2.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/whatsapp-image-2026-06-02-at-4-20-05-pm-1\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"223\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-1-300x223.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-1-300x223.jpeg 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-1-1024x760.jpeg 1024w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-1-768x570.jpeg 768w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-1-860x638.jpeg 860w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-1.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/whatsapp-image-2026-06-02-at-4-20-05-pm\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-300x225.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-300x225.jpeg 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-1024x768.jpeg 1024w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-768x576.jpeg 768w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM-860x645.jpeg 860w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.05-PM.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p>M\u00e1s San Miguel denunci\u00f3 un nuevo episodio de persecuci\u00f3n pol\u00edtica por parte del Municipio de San Miguel luego de que inspectores municipales notificaran un acta de suspensi\u00f3n y una amenaza de clausura durante la realizaci\u00f3n de una nueva fecha de Eje de la Rima, un evento cultural y juvenil que se desarrolla mensualmente en su [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[4],"tags":[],"class_list":["post-15959","post","type-post","status-publish","format-standard","category-politica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura - Diario del Oeste<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura - Diario del Oeste\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s San Miguel denunci\u00f3 un nuevo episodio de persecuci\u00f3n pol\u00edtica por parte del Municipio de San Miguel luego de que inspectores municipales notificaran un acta de suspensi\u00f3n y una amenaza de clausura durante la realizaci\u00f3n de una nueva fecha de Eje de la Rima, un evento cultural y juvenil que se desarrolla mensualmente en su [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario del Oeste\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-02T19:34:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM-300x225.jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/\"},\"author\":{\"name\":\"Redaccion\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/person\\\/1f7be965f8c093432e1cbfcee0ac4047\"},\"headline\":\"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura\",\"datePublished\":\"2026-06-02T19:34:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/\"},\"wordCount\":477,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-1024x768.jpeg\",\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/\",\"name\":\"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura - Diario del Oeste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-1024x768.jpeg\",\"datePublished\":\"2026-06-02T19:34:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-02-at-4.20.04-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/WhatsApp-Image-2026-06-02-at-4.20.04-PM.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/02\\\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"name\":\"Diario del Oeste\",\"description\":\"Noticias del Oeste\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\",\"name\":\"Diario del Oeste\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"width\":306,\"height\":145,\"caption\":\"Diario del Oeste\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/person\\\/1f7be965f8c093432e1cbfcee0ac4047\",\"name\":\"Redaccion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g\",\"caption\":\"Redaccion\"},\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura - Diario del Oeste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura - Diario del Oeste","og_description":"M\u00e1s San Miguel denunci\u00f3 un nuevo episodio de persecuci\u00f3n pol\u00edtica por parte del Municipio de San Miguel luego de que inspectores municipales notificaran un acta de suspensi\u00f3n y una amenaza de clausura durante la realizaci\u00f3n de una nueva fecha de Eje de la Rima, un evento cultural y juvenil que se desarrolla mensualmente en su [&hellip;]","og_url":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/","og_site_name":"Diario del Oeste","article_published_time":"2026-06-02T19:34:26+00:00","og_image":[{"url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.06-PM-300x225.jpeg","type":"","width":"","height":""}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redaccion","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/#article","isPartOf":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/"},"author":{"name":"Redaccion","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/person\/1f7be965f8c093432e1cbfcee0ac4047"},"headline":"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura","datePublished":"2026-06-02T19:34:26+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/"},"wordCount":477,"publisher":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#organization"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-1024x768.jpeg","articleSection":["Pol\u00edtica"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/","url":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/","name":"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura - Diario del Oeste","isPartOf":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/#primaryimage"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM-1024x768.jpeg","datePublished":"2026-06-02T19:34:26+00:00","breadcrumb":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/#primaryimage","url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM.jpeg","contentUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/WhatsApp-Image-2026-06-02-at-4.20.04-PM.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/02\/mas-san-miguel-denuncia-persecucion-politica-tras-una-amenaza-de-clausura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/diariodeloeste.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s San Miguel denuncia persecuci\u00f3n pol\u00edtica tras una amenaza de clausura"}]},{"@type":"WebSite","@id":"https:\/\/diariodeloeste.com\/noticias\/#website","url":"https:\/\/diariodeloeste.com\/noticias\/","name":"Diario del Oeste","description":"Noticias del Oeste","publisher":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodeloeste.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/diariodeloeste.com\/noticias\/#organization","name":"Diario del Oeste","url":"https:\/\/diariodeloeste.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","contentUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","width":306,"height":145,"caption":"Diario del Oeste"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/person\/1f7be965f8c093432e1cbfcee0ac4047","name":"Redaccion","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g","caption":"Redaccion"},"url":"https:\/\/diariodeloeste.com\/noticias\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/15959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/comments?post=15959"}],"version-history":[{"count":1,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/15959\/revisions"}],"predecessor-version":[{"id":15966,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/15959\/revisions\/15966"}],"wp:attachment":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/media?parent=15959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/categories?post=15959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/tags?post=15959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}