{"id":15951,"date":"2026-06-01T19:16:49","date_gmt":"2026-06-01T19:16:49","guid":{"rendered":"https:\/\/diariodeloeste.com\/noticias\/?p=15951"},"modified":"2026-06-02T14:04:52","modified_gmt":"2026-06-02T14:04:52","slug":"san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026","status":"publish","type":"post","link":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/","title":{"rendered":"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026"},"content":{"rendered":"<div>\n<div class=\"yiv7603132638gmail_quote\">\n<div dir=\"ltr\">\n<div dir=\"ltr\">\n<div class=\"yiv7603132638gmail_quote\">\n<div>\n<div id='gallery-1' class='gallery galleryid-15951 gallery-columns-4 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2025\/10\/13\/san-miguel-celebro-los-10-anos-del-centro-de-desarrollo-infanto-familiar-del-polo\/captura-de-pantalla-351\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"212\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-351-300x212.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-351-300x212.png 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-351.png 346w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2025\/10\/13\/san-miguel-celebro-los-10-anos-del-centro-de-desarrollo-infanto-familiar-del-polo\/captura-de-pantalla-348\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"217\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-348-300x217.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-348-300x217.png 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-348.png 343w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2025\/10\/13\/san-miguel-celebro-los-10-anos-del-centro-de-desarrollo-infanto-familiar-del-polo\/captura-de-pantalla-347\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"218\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-347-300x218.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-347-300x218.png 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-347.png 346w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/diariodeloeste.com\/noticias\/2025\/10\/13\/san-miguel-celebro-los-10-anos-del-centro-de-desarrollo-infanto-familiar-del-polo\/captura-de-pantalla-344\/'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"214\" src=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-344-300x214.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-344-300x214.png 300w, https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-344.png 351w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<h2>La Municipalidad de San Miguel firm\u00f3 un convenio esta semana con la empresa Educabot para realizar en el distrito la semifinal de la Copa Rob\u00f3tica Educabot 2026, un certamen educativo de alcance federal.<\/p>\n<p>En este marco, se reunieron en la Usina Tecnol\u00f3gica (UTEC) el intendente de San Miguel, Jaime M\u00e9ndez; el secretario de Educaci\u00f3n y Trabajo, Andr\u00e9s Lagalaye, y los CEO de Educabot, Micaela Unamuno y Felipe Herrera Zoppi, entre otras autoridades del municipio y la empresa.<\/p>\n<p>Se trata de un certamen que busca promover el desarrollo de competencias en rob\u00f3tica, programaci\u00f3n e inteligencia artificial, bajo un enfoque STEAM (ciencia, tecnolog\u00eda, ingenier\u00eda, arte y matem\u00e1ticas).<\/p>\n<p>En esta instancia, participar\u00e1n 147 escuelas, 280 equipos de estudiantes y docentes de toda la provincia de Buenos Aires. Adem\u00e1s, dos equipos clasificar\u00e1n a la final nacional que se realizar\u00e1 en Neuqu\u00e9n y el equipo ganador representar\u00e1 a la Argentina en el Mundial de Rob\u00f3tica First Global Challenge.<\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div class=\"yiv7603132638gmail_quote\">\n<div dir=\"ltr\">\n<div dir=\"ltr\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<script>function PlayerjsAsync(){} if(window[\"Playerjs\"]){PlayerjsAsync();}<\/script>","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de San Miguel firm\u00f3 un convenio esta semana con la empresa Educabot para realizar en el distrito la semifinal de la Copa Rob\u00f3tica Educabot 2026, un certamen educativo de alcance federal. En este marco, se reunieron en la Usina Tecnol\u00f3gica (UTEC) el intendente de San Miguel, Jaime M\u00e9ndez; el secretario de Educaci\u00f3n y [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":15952,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[500],"tags":[],"class_list":["post-15951","post","type-post","status-publish","format-standard","has-post-thumbnail","category-san-miguel"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026 - Diario del Oeste<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026 - Diario del Oeste\" \/>\n<meta property=\"og:description\" content=\"La Municipalidad de San Miguel firm\u00f3 un convenio esta semana con la empresa Educabot para realizar en el distrito la semifinal de la Copa Rob\u00f3tica Educabot 2026, un certamen educativo de alcance federal. En este marco, se reunieron en la Usina Tecnol\u00f3gica (UTEC) el intendente de San Miguel, Jaime M\u00e9ndez; el secretario de Educaci\u00f3n y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario del Oeste\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-01T19:16:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T14:04:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaccion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaccion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/\"},\"author\":{\"name\":\"Redaccion\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/person\\\/1f7be965f8c093432e1cbfcee0ac4047\"},\"headline\":\"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026\",\"datePublished\":\"2026-06-01T19:16:49+00:00\",\"dateModified\":\"2026-06-02T14:04:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/\"},\"wordCount\":181,\"publisher\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg\",\"articleSection\":[\"San Miguel\"],\"inLanguage\":\"es-AR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/\",\"name\":\"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026 - Diario del Oeste\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg\",\"datePublished\":\"2026-06-01T19:16:49+00:00\",\"dateModified\":\"2026-06-02T14:04:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/#breadcrumb\"},\"inLanguage\":\"es-AR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg\",\"contentUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/2026\\\/06\\\/01\\\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#website\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"name\":\"Diario del Oeste\",\"description\":\"Noticias del Oeste\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-AR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#organization\",\"name\":\"Diario del Oeste\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/logo.png\",\"width\":306,\"height\":145,\"caption\":\"Diario del Oeste\"},\"image\":{\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/#\\\/schema\\\/person\\\/1f7be965f8c093432e1cbfcee0ac4047\",\"name\":\"Redaccion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-AR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g\",\"caption\":\"Redaccion\"},\"url\":\"https:\\\/\\\/diariodeloeste.com\\\/noticias\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026 - Diario del Oeste","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/","og_locale":"es_ES","og_type":"article","og_title":"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026 - Diario del Oeste","og_description":"La Municipalidad de San Miguel firm\u00f3 un convenio esta semana con la empresa Educabot para realizar en el distrito la semifinal de la Copa Rob\u00f3tica Educabot 2026, un certamen educativo de alcance federal. En este marco, se reunieron en la Usina Tecnol\u00f3gica (UTEC) el intendente de San Miguel, Jaime M\u00e9ndez; el secretario de Educaci\u00f3n y [&hellip;]","og_url":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/","og_site_name":"Diario del Oeste","article_published_time":"2026-06-01T19:16:49+00:00","article_modified_time":"2026-06-02T14:04:52+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg","type":"image\/jpeg"}],"author":"Redaccion","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redaccion","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/#article","isPartOf":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/"},"author":{"name":"Redaccion","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/person\/1f7be965f8c093432e1cbfcee0ac4047"},"headline":"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026","datePublished":"2026-06-01T19:16:49+00:00","dateModified":"2026-06-02T14:04:52+00:00","mainEntityOfPage":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/"},"wordCount":181,"publisher":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#organization"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg","articleSection":["San Miguel"],"inLanguage":"es-AR"},{"@type":"WebPage","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/","url":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/","name":"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026 - Diario del Oeste","isPartOf":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/#primaryimage"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg","datePublished":"2026-06-01T19:16:49+00:00","dateModified":"2026-06-02T14:04:52+00:00","breadcrumb":{"@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/#breadcrumb"},"inLanguage":"es-AR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/#primaryimage","url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg","contentUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2026\/06\/San-Miguel-sera-sede-provincial-de-la-Copa-Robotica-Educabot-2026.jpg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/diariodeloeste.com\/noticias\/2026\/06\/01\/san-miguel-sera-sede-provincial-de-la-copa-robotica-educabot-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/diariodeloeste.com\/noticias\/"},{"@type":"ListItem","position":2,"name":"San Miguel ser\u00e1 sede provincial de la Copa Rob\u00f3tica Educabot 2026"}]},{"@type":"WebSite","@id":"https:\/\/diariodeloeste.com\/noticias\/#website","url":"https:\/\/diariodeloeste.com\/noticias\/","name":"Diario del Oeste","description":"Noticias del Oeste","publisher":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariodeloeste.com\/noticias\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-AR"},{"@type":"Organization","@id":"https:\/\/diariodeloeste.com\/noticias\/#organization","name":"Diario del Oeste","url":"https:\/\/diariodeloeste.com\/noticias\/","logo":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/","url":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","contentUrl":"https:\/\/diariodeloeste.com\/noticias\/wp-content\/uploads\/2019\/04\/logo.png","width":306,"height":145,"caption":"Diario del Oeste"},"image":{"@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/diariodeloeste.com\/noticias\/#\/schema\/person\/1f7be965f8c093432e1cbfcee0ac4047","name":"Redaccion","image":{"@type":"ImageObject","inLanguage":"es-AR","@id":"https:\/\/secure.gravatar.com\/avatar\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9bc3a12e26b32d818d88f9a5b61de20b559752e499df507efa7ea3cea0550ef?s=96&d=mm&r=g","caption":"Redaccion"},"url":"https:\/\/diariodeloeste.com\/noticias\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/15951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/comments?post=15951"}],"version-history":[{"count":2,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/15951\/revisions"}],"predecessor-version":[{"id":15954,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/posts\/15951\/revisions\/15954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/media\/15952"}],"wp:attachment":[{"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/media?parent=15951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/categories?post=15951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariodeloeste.com\/noticias\/wp-json\/wp\/v2\/tags?post=15951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}